{"id":1819,"date":"2022-10-28T16:07:39","date_gmt":"2022-10-28T14:07:39","guid":{"rendered":"https:\/\/2022.bto.travel\/speaker\/manuela-laiacona\/"},"modified":"2022-11-12T11:27:32","modified_gmt":"2022-11-12T09:27:32","slug":"manuela-laiacona","status":"publish","type":"speakers","link":"https:\/\/2022.bto.travel\/en\/speaker\/manuela-laiacona\/","title":{"rendered":"Manuela Laiacona"},"content":{"rendered":"<p>Food and Wine Writer. Journalist. Managing director and Communication&amp;Pr Manager of Catasta Pollino, Pollino National Park&#8217;s main tourism and cultural hub.<\/p>\n","protected":false},"author":1,"featured_media":1338,"template":"","acf":{"azienda":"Catasta Pollino","email":"manuela_laiacona@hotmail.it","ruolo":"Managing Director","bidir_speaker_event":[1818],"social_linkedin":"","ordinamento":"Laiacona","modalita_partecipazione":"In presenza"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Manuela Laiacona - Be Travel Onlife<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/2022.bto.travel\/en\/speaker\/manuela-laiacona\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manuela Laiacona - Be Travel Onlife\" \/>\n<meta property=\"og:description\" content=\"Food and Wine Writer. Journalist. Managing director and Communication&amp;Pr Manager of Catasta Pollino, Pollino National Park&#8217;s main tourism and cultural hub.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/2022.bto.travel\/en\/speaker\/manuela-laiacona\/\" \/>\n<meta property=\"og:site_name\" content=\"Be Travel Onlife\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BTO.Official\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-12T09:27:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/2022.bto.travel\/wp-content\/uploads\/2022\/10\/Manuela-Laiacona-Foto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"958\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BTO_travel\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/2022.bto.travel\/en\/speaker\/manuela-laiacona\/\",\"url\":\"https:\/\/2022.bto.travel\/en\/speaker\/manuela-laiacona\/\",\"name\":\"Manuela Laiacona - Be Travel Onlife\",\"isPartOf\":{\"@id\":\"https:\/\/2022.bto.travel\/#website\"},\"datePublished\":\"2022-10-28T14:07:39+00:00\",\"dateModified\":\"2022-11-12T09:27:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/2022.bto.travel\/en\/speaker\/manuela-laiacona\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/2022.bto.travel\/en\/speaker\/manuela-laiacona\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/2022.bto.travel\/en\/speaker\/manuela-laiacona\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/2022.bto.travel\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Speaker\",\"item\":\"https:\/\/2022.bto.travel\/speaker\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Manuela Laiacona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/2022.bto.travel\/#website\",\"url\":\"https:\/\/2022.bto.travel\/\",\"name\":\"Be Travel Onlife\",\"description\":\"BTO 2023: 22-23 novembre 2023 \u2013 Stazione Leopolda, Firenze\",\"publisher\":{\"@id\":\"https:\/\/2022.bto.travel\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/2022.bto.travel\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/2022.bto.travel\/#organization\",\"name\":\"Be Travel Onlife\",\"url\":\"https:\/\/2022.bto.travel\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/2022.bto.travel\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/2022.bto.travel\/wp-content\/uploads\/2022\/09\/Logo-Bto-2022.png\",\"contentUrl\":\"https:\/\/2022.bto.travel\/wp-content\/uploads\/2022\/09\/Logo-Bto-2022.png\",\"width\":109,\"height\":41,\"caption\":\"Be Travel Onlife\"},\"image\":{\"@id\":\"https:\/\/2022.bto.travel\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/BTO.Official\/\",\"https:\/\/twitter.com\/BTO_travel\",\"https:\/\/www.instagram.com\/bto_betravelonlife\/\",\"https:\/\/www.youtube.com\/c\/BTOOfficialVideo\",\"https:\/\/www.linkedin.com\/company\/bto-be-travel-onlife\/mycompany\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manuela Laiacona - Be Travel Onlife","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/2022.bto.travel\/en\/speaker\/manuela-laiacona\/","og_locale":"en_US","og_type":"article","og_title":"Manuela Laiacona - Be Travel Onlife","og_description":"Food and Wine Writer. Journalist. Managing director and Communication&amp;Pr Manager of Catasta Pollino, Pollino National Park&#8217;s main tourism and cultural hub.","og_url":"https:\/\/2022.bto.travel\/en\/speaker\/manuela-laiacona\/","og_site_name":"Be Travel Onlife","article_publisher":"https:\/\/www.facebook.com\/BTO.Official\/","article_modified_time":"2022-11-12T09:27:32+00:00","og_image":[{"width":960,"height":958,"url":"https:\/\/2022.bto.travel\/wp-content\/uploads\/2022\/10\/Manuela-Laiacona-Foto.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@BTO_travel","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/2022.bto.travel\/en\/speaker\/manuela-laiacona\/","url":"https:\/\/2022.bto.travel\/en\/speaker\/manuela-laiacona\/","name":"Manuela Laiacona - Be Travel Onlife","isPartOf":{"@id":"https:\/\/2022.bto.travel\/#website"},"datePublished":"2022-10-28T14:07:39+00:00","dateModified":"2022-11-12T09:27:32+00:00","breadcrumb":{"@id":"https:\/\/2022.bto.travel\/en\/speaker\/manuela-laiacona\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/2022.bto.travel\/en\/speaker\/manuela-laiacona\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/2022.bto.travel\/en\/speaker\/manuela-laiacona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/2022.bto.travel\/en\/"},{"@type":"ListItem","position":2,"name":"Speaker","item":"https:\/\/2022.bto.travel\/speaker\/"},{"@type":"ListItem","position":3,"name":"Manuela Laiacona"}]},{"@type":"WebSite","@id":"https:\/\/2022.bto.travel\/#website","url":"https:\/\/2022.bto.travel\/","name":"Be Travel Onlife","description":"BTO 2023: 22-23 novembre 2023 \u2013 Stazione Leopolda, Firenze","publisher":{"@id":"https:\/\/2022.bto.travel\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/2022.bto.travel\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/2022.bto.travel\/#organization","name":"Be Travel Onlife","url":"https:\/\/2022.bto.travel\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/2022.bto.travel\/#\/schema\/logo\/image\/","url":"https:\/\/2022.bto.travel\/wp-content\/uploads\/2022\/09\/Logo-Bto-2022.png","contentUrl":"https:\/\/2022.bto.travel\/wp-content\/uploads\/2022\/09\/Logo-Bto-2022.png","width":109,"height":41,"caption":"Be Travel Onlife"},"image":{"@id":"https:\/\/2022.bto.travel\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BTO.Official\/","https:\/\/twitter.com\/BTO_travel","https:\/\/www.instagram.com\/bto_betravelonlife\/","https:\/\/www.youtube.com\/c\/BTOOfficialVideo","https:\/\/www.linkedin.com\/company\/bto-be-travel-onlife\/mycompany\/"]}]}},"_links":{"self":[{"href":"https:\/\/2022.bto.travel\/en\/wp-json\/wp\/v2\/speakers\/1819"}],"collection":[{"href":"https:\/\/2022.bto.travel\/en\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/2022.bto.travel\/en\/wp-json\/wp\/v2\/types\/speakers"}],"author":[{"embeddable":true,"href":"https:\/\/2022.bto.travel\/en\/wp-json\/wp\/v2\/users\/1"}],"acf:post":[{"embeddable":true,"href":"https:\/\/2022.bto.travel\/en\/wp-json\/wp\/v2\/eventi\/1818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/2022.bto.travel\/en\/wp-json\/wp\/v2\/media\/1338"}],"wp:attachment":[{"href":"https:\/\/2022.bto.travel\/en\/wp-json\/wp\/v2\/media?parent=1819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}